{"id":3587,"date":"2013-05-23T02:22:04","date_gmt":"2013-05-23T02:22:04","guid":{"rendered":"http:\/\/www.arquimaster.com.ar\/web\/?p=3587"},"modified":"2014-02-16T02:32:29","modified_gmt":"2014-02-16T02:32:29","slug":"casa-la66-en-nordelta-epstein-arquitectos","status":"publish","type":"post","link":"https:\/\/www.arquimaster.com.ar\/web\/casa-la66-en-nordelta-epstein-arquitectos\/","title":{"rendered":"Casa LA66 en Nordelta \/ Epstein Arquitectos"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div><div class=\"b812932af2e751442846f039925109de\" data-index=\"1\" style=\"float: none; margin:25px 0 25px 0; text-align:center;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- Arquimaster (superior) -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-6351072698456832\"\r\n     data-ad-slot=\"6455489680\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p><strong>Casa LA66<\/strong> (Nordelta, Tigre, Pcia. Buenos Aires, Argentina) en <strong>Epstein Arquitectos<\/strong>. La casa LA66 est\u00e1 ubicada en un Barrio cerrado de la Zona Norte de la Provincia de Buenos Aires. Emplazada en un terreno de 18.5 metros de frente, fondo de 20 metros sobre laguna, y 40 metros de profundidad, con orientaci\u00f3n noroeste hacia la l\u00ednea de fondo.<\/p>\n<div id='gallery-1' class='gallery galleryid-3587 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_1b.jpg' title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rl_title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" class=\"rl-gallery-link\" data-rl_caption=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_1b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-3589\" srcset=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_1b-150x150.jpg 150w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_1b-50x50.jpg 50w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_1b-125x125.jpg 125w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3589'>\n\t\t\t\tCasa LA66 en Nordelta \/ Epstein Arquitectos\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_6b.jpg' title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rl_title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" class=\"rl-gallery-link\" data-rl_caption=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_6b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-3594\" srcset=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_6b-150x150.jpg 150w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_6b-50x50.jpg 50w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_6b-125x125.jpg 125w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3594'>\n\t\t\t\tCasa LA66 en Nordelta \/ Epstein Arquitectos\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_3b.jpg' title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rl_title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" class=\"rl-gallery-link\" data-rl_caption=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_3b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-3591\" srcset=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_3b-150x150.jpg 150w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_3b-50x50.jpg 50w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_3b-125x125.jpg 125w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3591'>\n\t\t\t\tCasa LA66 en Nordelta \/ Epstein Arquitectos\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_4b.jpg' title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rl_title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" class=\"rl-gallery-link\" data-rl_caption=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_4b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-3592\" srcset=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_4b-150x150.jpg 150w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_4b-50x50.jpg 50w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_4b-125x125.jpg 125w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3592'>\n\t\t\t\tCasa LA66 en Nordelta \/ Epstein Arquitectos\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_5b.jpg' title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rl_title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" class=\"rl-gallery-link\" data-rl_caption=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_5b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-3593\" srcset=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_5b-150x150.jpg 150w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_5b-50x50.jpg 50w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_5b-125x125.jpg 125w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3593'>\n\t\t\t\tCasa LA66 en Nordelta \/ Epstein Arquitectos\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_7b.jpg' title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rl_title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" class=\"rl-gallery-link\" data-rl_caption=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_7b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-3595\" srcset=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_7b-150x150.jpg 150w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_7b-50x50.jpg 50w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_7b-125x125.jpg 125w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3595'>\n\t\t\t\tCasa LA66 en Nordelta \/ Epstein Arquitectos\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_2b.jpg' title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rl_title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" class=\"rl-gallery-link\" data-rl_caption=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_2b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-3590\" srcset=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_2b-150x150.jpg 150w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_2b-50x50.jpg 50w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_2b-125x125.jpg 125w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3590'>\n\t\t\t\tCasa LA66 en Nordelta \/ Epstein Arquitectos\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_8b.jpg' title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rl_title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" class=\"rl-gallery-link\" data-rl_caption=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_8b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-3596\" srcset=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_8b-150x150.jpg 150w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_8b-50x50.jpg 50w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_8b-125x125.jpg 125w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3596'>\n\t\t\t\tCasa LA66 en Nordelta \/ Epstein Arquitectos\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_9b.jpg' title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rl_title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" class=\"rl-gallery-link\" data-rl_caption=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_9b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-3597\" srcset=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_9b-150x150.jpg 150w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_9b-50x50.jpg 50w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_9b-125x125.jpg 125w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3597'>\n\t\t\t\tCasa LA66 en Nordelta \/ Epstein Arquitectos\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_10b.jpg' title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rl_title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" class=\"rl-gallery-link\" data-rl_caption=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_10b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-3598\" srcset=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_10b-150x150.jpg 150w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_10b-50x50.jpg 50w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_10b-125x125.jpg 125w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3598'>\n\t\t\t\tCasa LA66 en Nordelta \/ Epstein Arquitectos\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_11b.jpg' title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rl_title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" class=\"rl-gallery-link\" data-rl_caption=\"Casa LA66 en Nordelta \/ Epstein Arquitectos\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_11b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-3599\" srcset=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_11b-150x150.jpg 150w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_11b-50x50.jpg 50w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_11b-125x125.jpg 125w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3599'>\n\t\t\t\tCasa LA66 en Nordelta \/ Epstein Arquitectos\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_pb.jpg' title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos (planta baja)\" data-rl_title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos (planta baja)\" class=\"rl-gallery-link\" data-rl_caption=\"Casa LA66 en Nordelta \/ Epstein Arquitectos (planta baja)\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_pb-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-3601\" srcset=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_pb-150x150.jpg 150w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_pb-50x50.jpg 50w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_pb-125x125.jpg 125w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3601'>\n\t\t\t\tCasa LA66 en Nordelta \/ Epstein Arquitectos (planta baja)\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_pa.jpg' title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos (planta alta)\" data-rl_title=\"Casa LA66 en Nordelta \/ Epstein Arquitectos (planta alta)\" class=\"rl-gallery-link\" data-rl_caption=\"Casa LA66 en Nordelta \/ Epstein Arquitectos (planta alta)\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_pa-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-3600\" srcset=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_pa-150x150.jpg 150w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_pa-50x50.jpg 50w, https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_pa-125x125.jpg 125w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3600'>\n\t\t\t\tCasa LA66 en Nordelta \/ Epstein Arquitectos (planta alta)\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>La arquitectura de la casa se genera a partir de un programa funcional a las necesidades de los usuarios con las premisas de optimizar la superficie construible contemplando la<strong> ubicaci\u00f3n privilegiada sobre el lago<\/strong>.<\/p>\n<p>Se utiliz\u00f3 una estructura independiente, de hormig\u00f3n armado que nos dio la libertad deseada para poder articular los diferentes cuerpos de la vivienda,\u00a0<strong>desmaterializar las esquinas<\/strong>\u00a0y utilizar\u00a0<strong>grandes superficies vidriadas hacia el fondo para no limitar las visuales<\/strong>.<\/p>\n<p>Se utilizaron <strong>materiales nobles<\/strong>, como los planos vidriados, las diferentes texturas en los solados y revestimiento, fueron calificando y dando car\u00e1cter singular a los diferentes sectores respondiendo a las necesidades concretas de esta casa.<\/p>\n<p>De esta manera la\u00a0<strong>iluminaci\u00f3n <\/strong>artificial se toma como un material m\u00e1s que entra en sinton\u00eda con todas las partes que intervienen en el proyecto.<\/p>\n<p>Desde el punto de vista pragm\u00e1tico se busco lograr un <strong>dise\u00f1o \u00f3ptimo y de calidad espacial<\/strong>, la vivienda se estructura en dos niveles diferentes.<\/p>\n<p>En planta baja se ubican los <strong>sectores sociales y \u00e1reas de servicios <\/strong>y un nivel superior que se destino al\u00a0<strong>\u00e1rea privada y de descanso <\/strong>ubic\u00e1ndose all\u00ed los dormitorios de los hijos y la suite principal.<\/p>\n<p>Sobre el frente la entrada se marca entre un volumen independiente que funciona como cochera insertado por debajo de la planta alta y una carpinter\u00eda despegada del muro, delimitando el escritorio a medida que se avanza en el interior se plantea un <strong>eje central visual<\/strong>, que nos conduce hacia un\u00a0<strong>espacio transparente y abierto que se despliega al jard\u00edn y el lago<\/strong>.<\/p>\n<p>La escalera y el hall se alinea con un eje transversal que atraviesa todo la casa, configurando un \u00fanico espacio que conecta los dos vol\u00famenes principales del proyecto, as\u00ed este conector funciona como <strong>pulm\u00f3n incorporando visuales continuas y entrada de luz natural<\/strong> en ambos niveles.<\/p>\n<p>El\u00a0living-comedor se abre sobre la costa del lago, este mismo se expande al exterior a trav\u00e9s de una <strong>galer\u00eda cubierta<\/strong> que funciona como <strong>transici\u00f3n y expansi\u00f3n al exterior<\/strong>.<\/p>\n<p>La\u00a0cocina\u00a0est\u00e1 completamente integrada al living conformando as\u00ed un \u00fanico espacio junto con el comedor y living.<\/p>\n<p>En la planta alta las habitaciones est\u00e1n armadas en dos cuerpos separados por el hall en una circulaci\u00f3n lineal y simple para acceder a estas.<\/p>\n<p>El\u00a0dormitorio principal, compuesto por un vestidor y ba\u00f1o, abiertos a una\u00a0<strong>terraza <\/strong>delimitada y contenida por una <strong>viga perimetral<\/strong> que <strong>enmarcan la vista al lago y tamizan la entrada de luz natural<\/strong>.<\/p>\n<p>La <strong>integraci\u00f3n de espacios<\/strong> que contienen por su escala desarrollados en una marcada horizontalidad de la volumetr\u00eda implantada sobre las costa del lago potenciando este concepto, de recorrido simple, \u00e9nfasis en la <strong>transparencia, entrada de luz natural\u00a0y continuidad visual<\/strong> es una b\u00fasqueda que se materializa finalmente en el conjunto del proyecto.<\/p>\n<p><strong>Ficha t\u00e9cnica<\/strong><br \/>\nObra: Casa LA66<br \/>\nUbicaci\u00f3n: Nordelta, Partido de Tigre, Pcia. Buenos Aires, Argentina<br \/>\nProyecto y Direcci\u00f3n: Epstein arquitectos<br \/>\nColaboradores: Arq. Pedro Aulenta, Arq. Romina Gagliarducci, Arq. Roc\u00edo Folgueira<br \/>\nConstrucci\u00f3n: Epstein Arquitectos<br \/>\nA\u00f1o de ejecuci\u00f3n: 2012<br \/>\nSuperficie terreno: 773 m2<br \/>\nSuperficie construida: 347 m2<\/p>\n<p><strong>Contacto<\/strong>: <a href=\"http:\/\/www.epsteinarquitectos.com\" target=\"_blank\">http:\/\/www.epsteinarquitectos.com<\/a><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>","protected":false},"excerpt":{"rendered":"<p>Un espacio transparente y abierto se despliega al jard\u00edn y el lago incorporando visuales&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3588,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[1,83],"tags":[16,847,846,897,984,945,254],"class_list":["post-3587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyecto","category-vivienda-unifamiliar","tag-buenos-aires","tag-casa-en-barrio-cerrado","tag-casa-en-country","tag-epstein-arquitectos","tag-nordelta","tag-tigre","tag-vivienda-unifamiliar-2","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casa LA66 en Nordelta \/ Epstein Arquitectos - Arquimaster<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arquimaster.com.ar\/web\/casa-la66-en-nordelta-epstein-arquitectos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casa LA66 en Nordelta \/ Epstein Arquitectos - Arquimaster\" \/>\n<meta property=\"og:description\" content=\"Un espacio transparente y abierto se despliega al jard\u00edn y el lago incorporando visuales...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arquimaster.com.ar\/web\/casa-la66-en-nordelta-epstein-arquitectos\/\" \/>\n<meta property=\"og:site_name\" content=\"Arquimaster\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/ARQUIMASTER.com.ar\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-23T02:22:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-02-16T02:32:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_slide.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"642\" \/>\n\t<meta property=\"og:image:height\" content=\"336\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arquimaster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@arquimaster\" \/>\n<meta name=\"twitter:site\" content=\"@arquimaster\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arquimaster\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/casa-la66-en-nordelta-epstein-arquitectos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/casa-la66-en-nordelta-epstein-arquitectos\\\/\"},\"author\":{\"name\":\"Arquimaster\",\"@id\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/#\\\/schema\\\/person\\\/359e9f7c00193fcde068e0dd2ceb0028\"},\"headline\":\"Casa LA66 en Nordelta \\\/ Epstein Arquitectos\",\"datePublished\":\"2013-05-23T02:22:04+00:00\",\"dateModified\":\"2014-02-16T02:32:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/casa-la66-en-nordelta-epstein-arquitectos\\\/\"},\"wordCount\":599,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/casa-la66-en-nordelta-epstein-arquitectos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/casa_la66_slide.jpg\",\"keywords\":[\"Buenos Aires\",\"casa en barrio cerrado\",\"casa en country\",\"Epstein Arquitectos\",\"Nordelta\",\"Tigre\",\"vivienda unifamiliar\"],\"articleSection\":[\"Proyecto\",\"Vivienda unifamiliar y PH\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/casa-la66-en-nordelta-epstein-arquitectos\\\/\",\"url\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/casa-la66-en-nordelta-epstein-arquitectos\\\/\",\"name\":\"Casa LA66 en Nordelta \\\/ Epstein Arquitectos - Arquimaster\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/casa-la66-en-nordelta-epstein-arquitectos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/casa-la66-en-nordelta-epstein-arquitectos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/casa_la66_slide.jpg\",\"datePublished\":\"2013-05-23T02:22:04+00:00\",\"dateModified\":\"2014-02-16T02:32:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/casa-la66-en-nordelta-epstein-arquitectos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/casa-la66-en-nordelta-epstein-arquitectos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/casa-la66-en-nordelta-epstein-arquitectos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/casa_la66_slide.jpg\",\"contentUrl\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/casa_la66_slide.jpg\",\"width\":642,\"height\":336},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/casa-la66-en-nordelta-epstein-arquitectos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casa LA66 en Nordelta \\\/ Epstein Arquitectos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/\",\"name\":\"Arquimaster\",\"description\":\"Web de arquitectura, dise\u00f1o y construccion\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/#organization\",\"name\":\"Arquimaster\",\"url\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/arquimaster.png\",\"contentUrl\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/arquimaster.png\",\"width\":594,\"height\":78,\"caption\":\"Arquimaster\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/ARQUIMASTER.com.ar\",\"https:\\\/\\\/x.com\\\/arquimaster\",\"https:\\\/\\\/www.instagram.com\\\/arquimasterblog\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arquimaster\",\"https:\\\/\\\/www.pinterest.com\\\/arquimaster\",\"https:\\\/\\\/t.me\\\/arquimaster\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arquimaster.com.ar\\\/web\\\/#\\\/schema\\\/person\\\/359e9f7c00193fcde068e0dd2ceb0028\",\"name\":\"Arquimaster\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casa LA66 en Nordelta \/ Epstein Arquitectos - Arquimaster","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arquimaster.com.ar\/web\/casa-la66-en-nordelta-epstein-arquitectos\/","og_locale":"es_ES","og_type":"article","og_title":"Casa LA66 en Nordelta \/ Epstein Arquitectos - Arquimaster","og_description":"Un espacio transparente y abierto se despliega al jard\u00edn y el lago incorporando visuales...","og_url":"https:\/\/www.arquimaster.com.ar\/web\/casa-la66-en-nordelta-epstein-arquitectos\/","og_site_name":"Arquimaster","article_publisher":"http:\/\/www.facebook.com\/ARQUIMASTER.com.ar","article_published_time":"2013-05-23T02:22:04+00:00","article_modified_time":"2014-02-16T02:32:29+00:00","og_image":[{"width":642,"height":336,"url":"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_slide.jpg","type":"image\/jpeg"}],"author":"Arquimaster","twitter_card":"summary_large_image","twitter_creator":"@arquimaster","twitter_site":"@arquimaster","twitter_misc":{"Escrito por":"Arquimaster","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arquimaster.com.ar\/web\/casa-la66-en-nordelta-epstein-arquitectos\/#article","isPartOf":{"@id":"https:\/\/www.arquimaster.com.ar\/web\/casa-la66-en-nordelta-epstein-arquitectos\/"},"author":{"name":"Arquimaster","@id":"https:\/\/www.arquimaster.com.ar\/web\/#\/schema\/person\/359e9f7c00193fcde068e0dd2ceb0028"},"headline":"Casa LA66 en Nordelta \/ Epstein Arquitectos","datePublished":"2013-05-23T02:22:04+00:00","dateModified":"2014-02-16T02:32:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arquimaster.com.ar\/web\/casa-la66-en-nordelta-epstein-arquitectos\/"},"wordCount":599,"publisher":{"@id":"https:\/\/www.arquimaster.com.ar\/web\/#organization"},"image":{"@id":"https:\/\/www.arquimaster.com.ar\/web\/casa-la66-en-nordelta-epstein-arquitectos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_slide.jpg","keywords":["Buenos Aires","casa en barrio cerrado","casa en country","Epstein Arquitectos","Nordelta","Tigre","vivienda unifamiliar"],"articleSection":["Proyecto","Vivienda unifamiliar y PH"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.arquimaster.com.ar\/web\/casa-la66-en-nordelta-epstein-arquitectos\/","url":"https:\/\/www.arquimaster.com.ar\/web\/casa-la66-en-nordelta-epstein-arquitectos\/","name":"Casa LA66 en Nordelta \/ Epstein Arquitectos - Arquimaster","isPartOf":{"@id":"https:\/\/www.arquimaster.com.ar\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arquimaster.com.ar\/web\/casa-la66-en-nordelta-epstein-arquitectos\/#primaryimage"},"image":{"@id":"https:\/\/www.arquimaster.com.ar\/web\/casa-la66-en-nordelta-epstein-arquitectos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_slide.jpg","datePublished":"2013-05-23T02:22:04+00:00","dateModified":"2014-02-16T02:32:29+00:00","breadcrumb":{"@id":"https:\/\/www.arquimaster.com.ar\/web\/casa-la66-en-nordelta-epstein-arquitectos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arquimaster.com.ar\/web\/casa-la66-en-nordelta-epstein-arquitectos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arquimaster.com.ar\/web\/casa-la66-en-nordelta-epstein-arquitectos\/#primaryimage","url":"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_slide.jpg","contentUrl":"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_slide.jpg","width":642,"height":336},{"@type":"BreadcrumbList","@id":"https:\/\/www.arquimaster.com.ar\/web\/casa-la66-en-nordelta-epstein-arquitectos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.arquimaster.com.ar\/web\/"},{"@type":"ListItem","position":2,"name":"Casa LA66 en Nordelta \/ Epstein Arquitectos"}]},{"@type":"WebSite","@id":"https:\/\/www.arquimaster.com.ar\/web\/#website","url":"https:\/\/www.arquimaster.com.ar\/web\/","name":"Arquimaster","description":"Web de arquitectura, dise\u00f1o y construccion","publisher":{"@id":"https:\/\/www.arquimaster.com.ar\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arquimaster.com.ar\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.arquimaster.com.ar\/web\/#organization","name":"Arquimaster","url":"https:\/\/www.arquimaster.com.ar\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.arquimaster.com.ar\/web\/#\/schema\/logo\/image\/","url":"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2022\/06\/arquimaster.png","contentUrl":"https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2022\/06\/arquimaster.png","width":594,"height":78,"caption":"Arquimaster"},"image":{"@id":"https:\/\/www.arquimaster.com.ar\/web\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/ARQUIMASTER.com.ar","https:\/\/x.com\/arquimaster","https:\/\/www.instagram.com\/arquimasterblog\/","https:\/\/www.linkedin.com\/company\/arquimaster","https:\/\/www.pinterest.com\/arquimaster","https:\/\/t.me\/arquimaster"]},{"@type":"Person","@id":"https:\/\/www.arquimaster.com.ar\/web\/#\/schema\/person\/359e9f7c00193fcde068e0dd2ceb0028","name":"Arquimaster"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_slide.jpg",642,336,false],"thumbnail":["https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_slide-150x150.jpg",150,150,true],"medium":["https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_slide-300x157.jpg",300,157,true],"medium_large":["https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_slide.jpg",642,336,false],"large":["https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_slide.jpg",642,336,false],"1536x1536":["https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_slide.jpg",642,336,false],"2048x2048":["https:\/\/www.arquimaster.com.ar\/web\/wp-content\/uploads\/2014\/02\/casa_la66_slide.jpg",642,336,false]},"uagb_author_info":{"display_name":"Arquimaster","author_link":"https:\/\/www.arquimaster.com.ar\/web\/author\/arquimaster\/"},"uagb_comment_info":0,"uagb_excerpt":"Un espacio transparente y abierto se despliega al jard\u00edn y el lago incorporando visuales...","_links":{"self":[{"href":"https:\/\/www.arquimaster.com.ar\/web\/wp-json\/wp\/v2\/posts\/3587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arquimaster.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arquimaster.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arquimaster.com.ar\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arquimaster.com.ar\/web\/wp-json\/wp\/v2\/comments?post=3587"}],"version-history":[{"count":0,"href":"https:\/\/www.arquimaster.com.ar\/web\/wp-json\/wp\/v2\/posts\/3587\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arquimaster.com.ar\/web\/wp-json\/wp\/v2\/media\/3588"}],"wp:attachment":[{"href":"https:\/\/www.arquimaster.com.ar\/web\/wp-json\/wp\/v2\/media?parent=3587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arquimaster.com.ar\/web\/wp-json\/wp\/v2\/categories?post=3587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arquimaster.com.ar\/web\/wp-json\/wp\/v2\/tags?post=3587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}